{"id":200,"date":"2018-07-30T15:32:35","date_gmt":"2018-07-30T20:32:35","guid":{"rendered":"http:\/\/engineering3.flywheelsites.com\/xzeng\/wp-content\/uploads\/sites\/49\/2018\/07\/AFOSR-1.png"},"modified":"2018-07-30T15:32:35","modified_gmt":"2018-07-30T20:32:35","slug":"afosr-1","status":"inherit","type":"attachment","link":"https:\/\/ceid.utsa.edu\/xzeng\/home\/afosr-1\/","title":{"rendered":"AFOSR-1"},"author":41,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false},"class_list":["post-200","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AFOSR-1 - Xiaowei Zeng<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ceid.utsa.edu\/xzeng\/wp-content\/uploads\/sites\/49\/2018\/07\/AFOSR-1.png\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AFOSR-1 - Xiaowei Zeng\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ceid.utsa.edu\/xzeng\/wp-content\/uploads\/sites\/49\/2018\/07\/AFOSR-1.png\" \/>\n<meta property=\"og:site_name\" content=\"Xiaowei Zeng\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ceid.utsa.edu\/xzeng\/wp-content\/uploads\/sites\/49\/2018\/07\/AFOSR-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"225\" \/>\n\t<meta property=\"og:image:height\" content=\"225\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ceid.utsa.edu\\\/xzeng\\\/wp-content\\\/uploads\\\/sites\\\/49\\\/2018\\\/07\\\/AFOSR-1.png\",\"url\":\"https:\\\/\\\/ceid.utsa.edu\\\/xzeng\\\/wp-content\\\/uploads\\\/sites\\\/49\\\/2018\\\/07\\\/AFOSR-1.png\",\"name\":\"AFOSR-1 - Xiaowei Zeng\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ceid.utsa.edu\\\/xzeng\\\/#website\"},\"datePublished\":\"2018-07-30T20:32:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ceid.utsa.edu\\\/xzeng\\\/wp-content\\\/uploads\\\/sites\\\/49\\\/2018\\\/07\\\/AFOSR-1.png#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ceid.utsa.edu\\\/xzeng\\\/wp-content\\\/uploads\\\/sites\\\/49\\\/2018\\\/07\\\/AFOSR-1.png\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ceid.utsa.edu\\\/xzeng\\\/wp-content\\\/uploads\\\/sites\\\/49\\\/2018\\\/07\\\/AFOSR-1.png#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ceid.utsa.edu\\\/xzeng\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ceid.utsa.edu\\\/xzeng\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"AFOSR-1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ceid.utsa.edu\\\/xzeng\\\/#website\",\"url\":\"https:\\\/\\\/ceid.utsa.edu\\\/xzeng\\\/\",\"name\":\"Xiaowei Zeng\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ceid.utsa.edu\\\/xzeng\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ceid.utsa.edu\\\/xzeng\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ceid.utsa.edu\\\/xzeng\\\/#organization\",\"name\":\"UTSA College of Engineering\",\"url\":\"https:\\\/\\\/ceid.utsa.edu\\\/xzeng\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ceid.utsa.edu\\\/xzeng\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ceid.utsa.edu\\\/xzeng\\\/wp-content\\\/uploads\\\/sites\\\/49\\\/2017\\\/07\\\/cropped-COE-Casual-single.png\",\"contentUrl\":\"https:\\\/\\\/ceid.utsa.edu\\\/xzeng\\\/wp-content\\\/uploads\\\/sites\\\/49\\\/2017\\\/07\\\/cropped-COE-Casual-single.png\",\"width\":1932,\"height\":250,\"caption\":\"UTSA College of Engineering\"},\"image\":{\"@id\":\"https:\\\/\\\/ceid.utsa.edu\\\/xzeng\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AFOSR-1 - Xiaowei Zeng","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ceid.utsa.edu\/xzeng\/wp-content\/uploads\/sites\/49\/2018\/07\/AFOSR-1.png","og_locale":"en_US","og_type":"article","og_title":"AFOSR-1 - Xiaowei Zeng","og_url":"https:\/\/ceid.utsa.edu\/xzeng\/wp-content\/uploads\/sites\/49\/2018\/07\/AFOSR-1.png","og_site_name":"Xiaowei Zeng","og_image":[{"width":225,"height":225,"url":"https:\/\/ceid.utsa.edu\/xzeng\/wp-content\/uploads\/sites\/49\/2018\/07\/AFOSR-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ceid.utsa.edu\/xzeng\/wp-content\/uploads\/sites\/49\/2018\/07\/AFOSR-1.png","url":"https:\/\/ceid.utsa.edu\/xzeng\/wp-content\/uploads\/sites\/49\/2018\/07\/AFOSR-1.png","name":"AFOSR-1 - Xiaowei Zeng","isPartOf":{"@id":"https:\/\/ceid.utsa.edu\/xzeng\/#website"},"datePublished":"2018-07-30T20:32:35+00:00","breadcrumb":{"@id":"https:\/\/ceid.utsa.edu\/xzeng\/wp-content\/uploads\/sites\/49\/2018\/07\/AFOSR-1.png#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ceid.utsa.edu\/xzeng\/wp-content\/uploads\/sites\/49\/2018\/07\/AFOSR-1.png"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ceid.utsa.edu\/xzeng\/wp-content\/uploads\/sites\/49\/2018\/07\/AFOSR-1.png#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ceid.utsa.edu\/xzeng\/"},{"@type":"ListItem","position":2,"name":"Home","item":"https:\/\/ceid.utsa.edu\/xzeng\/"},{"@type":"ListItem","position":3,"name":"AFOSR-1"}]},{"@type":"WebSite","@id":"https:\/\/ceid.utsa.edu\/xzeng\/#website","url":"https:\/\/ceid.utsa.edu\/xzeng\/","name":"Xiaowei Zeng","description":"","publisher":{"@id":"https:\/\/ceid.utsa.edu\/xzeng\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ceid.utsa.edu\/xzeng\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ceid.utsa.edu\/xzeng\/#organization","name":"UTSA College of Engineering","url":"https:\/\/ceid.utsa.edu\/xzeng\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ceid.utsa.edu\/xzeng\/#\/schema\/logo\/image\/","url":"https:\/\/ceid.utsa.edu\/xzeng\/wp-content\/uploads\/sites\/49\/2017\/07\/cropped-COE-Casual-single.png","contentUrl":"https:\/\/ceid.utsa.edu\/xzeng\/wp-content\/uploads\/sites\/49\/2017\/07\/cropped-COE-Casual-single.png","width":1932,"height":250,"caption":"UTSA College of Engineering"},"image":{"@id":"https:\/\/ceid.utsa.edu\/xzeng\/#\/schema\/logo\/image\/"}}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/ceid.utsa.edu\/xzeng\/wp-content\/uploads\/sites\/49\/2018\/07\/AFOSR-1.png'><img fetchpriority=\"high\" decoding=\"async\" width=\"225\" height=\"225\" src=\"https:\/\/ceid.utsa.edu\/xzeng\/wp-content\/uploads\/sites\/49\/2018\/07\/AFOSR-1.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/ceid.utsa.edu\/xzeng\/wp-content\/uploads\/sites\/49\/2018\/07\/AFOSR-1.png 225w, https:\/\/ceid.utsa.edu\/xzeng\/wp-content\/uploads\/sites\/49\/2018\/07\/AFOSR-1-150x150.png 150w, https:\/\/ceid.utsa.edu\/xzeng\/wp-content\/uploads\/sites\/49\/2018\/07\/AFOSR-1-160x160.png 160w, https:\/\/ceid.utsa.edu\/xzeng\/wp-content\/uploads\/sites\/49\/2018\/07\/AFOSR-1-100x100.png 100w\" sizes=\"100vw\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":225,"height":225,"file":"2018\/07\/AFOSR-1.png","sizes":{"thumbnail":{"file":"AFOSR-1-150x150.png","width":150,"height":150,"mime_type":"image\/png","source_url":"https:\/\/ceid.utsa.edu\/xzeng\/wp-content\/uploads\/sites\/49\/2018\/07\/AFOSR-1-150x150.png"},"tshowcase-thumb":{"file":"AFOSR-1-160x160.png","width":160,"height":160,"mime_type":"image\/png","source_url":"https:\/\/ceid.utsa.edu\/xzeng\/wp-content\/uploads\/sites\/49\/2018\/07\/AFOSR-1-160x160.png"},"twentyseventeen-thumbnail-avatar":{"file":"AFOSR-1-100x100.png","width":100,"height":100,"mime_type":"image\/png","source_url":"https:\/\/ceid.utsa.edu\/xzeng\/wp-content\/uploads\/sites\/49\/2018\/07\/AFOSR-1-100x100.png"},"full":{"file":"AFOSR-1.png","width":225,"height":225,"mime_type":"image\/png","source_url":"https:\/\/ceid.utsa.edu\/xzeng\/wp-content\/uploads\/sites\/49\/2018\/07\/AFOSR-1.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":2,"source_url":"https:\/\/ceid.utsa.edu\/xzeng\/wp-content\/uploads\/sites\/49\/2018\/07\/AFOSR-1.png","filename":"AFOSR-1.png","filesize":94344,"_links":{"self":[{"href":"https:\/\/ceid.utsa.edu\/xzeng\/wp-json\/wp\/v2\/media\/200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ceid.utsa.edu\/xzeng\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/ceid.utsa.edu\/xzeng\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/ceid.utsa.edu\/xzeng\/wp-json\/wp\/v2\/users\/41"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":2,"href":"https:\/\/ceid.utsa.edu\/xzeng\/wp-json\/wp\/v2\/pages\/2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}